{"id":3132,"date":"2017-09-28T12:19:41","date_gmt":"2017-09-28T10:19:41","guid":{"rendered":"http:\/\/egroup.be\/?p=3132"},"modified":"2018-04-30T11:24:08","modified_gmt":"2018-04-30T09:24:08","slug":"integration-de-lergonomie-a-stade-entreprise","status":"publish","type":"post","link":"https:\/\/egroup.be\/fr\/integration-de-lergonomie-a-stade-entreprise\/","title":{"rendered":"Int\u00e9gration de l\u2019ergonomie : \u00e0 quel stade est votre entreprise ?"},"content":{"rendered":"<h3>L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9.<\/h3>\n<h4>Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?<\/h4>\n<p>&nbsp;<\/p>\n<h3>Stade 1 : Hostilit\u00e9 \u00e0 l\u2019ergonomie<\/h3>\n<p>L\u2019ergonomie est consid\u00e9r\u00e9e comme inutile ou tout au plus comme un ph\u00e9nom\u00e8ne de mode. Aucune attention particuli\u00e8re n\u2019est accord\u00e9e aux travailleurs ou aux clients. Les environnements de travail sont irr\u00e9fl\u00e9chis et les produits sont \u00ab vaguement fonctionnels \u00bb.<br \/>\nTout doit encore \u00eatre fait pour prendre conscience de la n\u00e9cessit\u00e9 de pr\u00eater attention aux deux \u00e9l\u00e9ments primordiaux de tout d\u00e9veloppement commercial : les travailleurs et les clients.<\/p>\n<h3>Stade 2 : Solution ergo-centrique<\/h3>\n<p>Quelques personnes dans l\u2019entreprise se sont rendu compte de dysfonctionnements : production peu efficace ou qualit\u00e9 de certains produits laissant \u00e0 d\u00e9sirer.<br \/>\nLe premier r\u00e9flexe \u00e0 ce stade est de tenter de solutionner les probl\u00e8mes en utilisant le bon sens. Qui se traduit par le mode de pens\u00e9e suivant : \u00ab Ce qui est bon pour moi, le sera pour les autres ! \u00bb.<br \/>\nCe stade pr\u00e9sente toutefois un aspect positif : une r\u00e9flexion est initi\u00e9e sur les probl\u00e9matiques identifi\u00e9es. Toutefois, les solutions s\u2019av\u00e8rent le plus souvent limit\u00e9es, car \u00e9(r)go-centriques et non fond\u00e9es sur une analyse globale et int\u00e9gr\u00e9e du travail.<\/p>\n<h3>Stade 3 : Ergonomie opportuniste<\/h3>\n<p>\u00c0 ce stade, il est clair pour plusieurs personnes que des efforts doivent \u00eatre faits pour solutionner certains probl\u00e8mes et am\u00e9liorer l\u2019ergonomie au sein de l\u2019entreprise. Des initiatives y naissent pour conduire la qualit\u00e9 des interventions \u00e0 un niveau sup\u00e9rieur. On se rend compte que se fier \u00e0 son intuition ou \u00e0 son bon sens n\u2019est probablement plus pertinent (ou trop risqu\u00e9), et des initiatives sont prises par certains managers pour recourir \u00e0 plus de m\u00e9thodologie. G\u00e9n\u00e9ralement, cela se traduit par le recours au conseil d\u2019un expert externe pour un projet ou par l\u2019utilisation de techniques sp\u00e9cifiques par une \u00e9quipe isol\u00e9e.<\/p>\n<h3>Stade 4 : Des budgets sont d\u00e9di\u00e9s \u00e0 l\u2019ergonomie<\/h3>\n<p>Les b\u00e9n\u00e9fices dus au recours \u00e0 l\u2019ergonomie ont \u00e9t\u00e9 remarqu\u00e9s. Les interventions isol\u00e9es ont amen\u00e9 des r\u00e9sultats : une unit\u00e9 de production a d\u00e9pass\u00e9 ses objectifs, un produit se d\u00e9marque par sa qualit\u00e9 exceptionnelle, les indicateurs de bien-\u00eatre sont au beau fixe. Toutes ces avanc\u00e9es ont \u00e9t\u00e9 remarqu\u00e9es par le top management qui trouve alors int\u00e9ressant d\u2019investir dans l\u2019am\u00e9lioration des environnements de travail et des produits.<br \/>\n\u00c0 ce stade, l\u2019ergonomie est ajout\u00e9e aux proc\u00e9dures de travail et planifi\u00e9e au sein des projets. Toutefois, les m\u00e9thodes utilis\u00e9es ne sont pas toujours les plus appropri\u00e9es. Elles sont souvent appliqu\u00e9es a post\u00e9riori, c\u2019est-\u00e0-dire trop tard (apr\u00e8s avoir constat\u00e9 les probl\u00e8mes) et non en d\u00e9but de projet, pour un impact marqu\u00e9.<\/p>\n<h3>Stade 5 : Gestion strat\u00e9gique de l\u2019ergonomie<\/h3>\n<p>L\u2019ergonomie a fait son chemin dans l\u2019entreprise. Les budgets ne sont pas \u00e9parpill\u00e9s mais centralis\u00e9s par un d\u00e9partement en charge de l\u2019ergonomie et de l\u2019utilisabilit\u00e9. Cette \u00e9quipe commence \u00e0 prendre de l\u2019ampleur et un espace de tests (un laboratoire par exemple) leur est m\u00eame allou\u00e9 afin d\u2019effectuer leurs analyses.<br \/>\nLes m\u00e9thodes se perfectionnent et deviennent de plus en plus fiables. Des archives des pr\u00e9c\u00e9dentes campagnes d\u2019am\u00e9lioration sont conserv\u00e9es et doucement germe l\u2019id\u00e9e que celles-ci peuvent aboutir \u00e0 un ensemble de bonnes pratiques qui vont guider l\u2019entreprise vers un niveau de maturit\u00e9 suppl\u00e9mentaire.<br \/>\nNote : Tr\u00e8s peu d\u2019entreprises ont atteint ce niveau de maturit\u00e9. Des \u00e9quipes sp\u00e9cialis\u00e9es commencent \u00e0 se mettre en place dans les grands groupes o\u00f9 des budgets peuvent \u00eatre d\u00e9gag\u00e9s.<\/p>\n<h3>Stade 6 : Ergonomie int\u00e9gr\u00e9e<\/h3>\n<p>\u00c0 ce stade, l\u2019ergonomie n\u2019est plus r\u00e9alis\u00e9e en surface, mais elle encadre les principaux projets de l\u2019entreprise. Elle a d\u00e9velopp\u00e9 et int\u00e9gr\u00e9 sa propre m\u00e9thodologie et a syst\u00e9matis\u00e9 ses processus.<br \/>\nL\u2019ergonomie est vue comme un processus it\u00e9ratif, ce qui implique la recherche de qualit\u00e9 progressive et continue dans l\u2019entreprise.<\/p>\n<h3>Stade 7 : Entreprise pilot\u00e9e par l\u2019ergonomie<\/h3>\n<p>C\u2019est le stade ultime de l\u2019int\u00e9gration de l\u2019ergonomie. Dans ce cas de figure, le d\u00e9veloppement de l\u2019organisation est pilot\u00e9 par les recherches sur ses travailleurs et ses clients. Ici, c\u2019est l\u2019exp\u00e9rience v\u00e9cue qui prime et la recherche constante des solutions les mieux adapt\u00e9es. L\u2019entreprise n\u2019est plus per\u00e7ue comme une somme de services ou de d\u00e9partements isol\u00e9s, mais comme un tout ou chaque \u00e9l\u00e9ment \u00e0 son r\u00f4le \u00e0 jouer dans la qualit\u00e9 et la performance.<\/p>\n<hr \/>\n<h4>Sources<\/h4>\n<p>Corporate Usability Maturity, Jakob Nielsen, Alertbox, April 24, 2006<\/p>\n<hr \/>\n<h3><\/h3>\n<h3>Plus d&#8217;informations ?<\/h3>\n<p><strong>Vous \u00eates charg\u00e9 d\u2019un projet pour lequel l\u2019ergonomie est une valeur ajout\u00e9e ? <\/strong> <a href=\"http:\/\/egroup.be\/fr\/#contact\">Contactez-nous pour un entretien d&#8217;information et\/ou pour b\u00e9n\u00e9ficier de nos services.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ? &nbsp; Stade 1 : Hostilit\u00e9 \u00e0 l\u2019ergonomie L\u2019ergonomie est consid\u00e9r\u00e9e comme inutile ou tout au plus comme un ph\u00e9nom\u00e8ne de mode. Aucune attention particuli\u00e8re n\u2019est accord\u00e9e aux [&hellip;]<\/p>","protected":false},"author":3,"featured_media":3233,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,2],"tags":[],"class_list":["post-3132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Int\u00e9gration de l\u2019ergonomie<\/title>\n<meta name=\"description\" content=\"L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egroup.be\/fr\/integration-de-lergonomie-a-stade-entreprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Int\u00e9gration de l\u2019ergonomie\" \/>\n<meta property=\"og:description\" content=\"L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egroup.be\/fr\/integration-de-lergonomie-a-stade-entreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"ergolabs group - UX \/ UI agency \/ usability\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T10:19:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-30T09:24:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"4000\" \/>\n\t<meta property=\"og:image:height\" content=\"2667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sacha Kocovski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sacha Kocovski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/\"},\"author\":{\"name\":\"Sacha Kocovski\",\"@id\":\"https:\/\/egroup.be\/#\/schema\/person\/fc2ba0627b169b6ea1d99818587a33df\"},\"headline\":\"Int\u00e9gration de l\u2019ergonomie : \u00e0 quel stade est votre entreprise ?\",\"datePublished\":\"2017-09-28T10:19:41+00:00\",\"dateModified\":\"2018-04-30T09:24:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/\"},\"wordCount\":859,\"publisher\":{\"@id\":\"https:\/\/egroup.be\/#organization\"},\"image\":{\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1\",\"articleSection\":[\"Articles\",\"blog\"],\"inLanguage\":\"fr-BE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/\",\"url\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/\",\"name\":\"Int\u00e9gration de l\u2019ergonomie\",\"isPartOf\":{\"@id\":\"https:\/\/egroup.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1\",\"datePublished\":\"2017-09-28T10:19:41+00:00\",\"dateModified\":\"2018-04-30T09:24:08+00:00\",\"description\":\"L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?\",\"breadcrumb\":{\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1\",\"width\":4000,\"height\":2667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/egroup.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Int\u00e9gration de l\u2019ergonomie : \u00e0 quel stade est votre entreprise ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/egroup.be\/#website\",\"url\":\"https:\/\/egroup.be\/\",\"name\":\"ergolabs group - Agence UX\/UI - ergonomie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/egroup.be\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/egroup.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/egroup.be\/#organization\",\"name\":\"ergolabs group sprl\",\"url\":\"https:\/\/egroup.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/egroup.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i1.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/LOGO-EG-clair-1200.png?fit=1200%2C222&ssl=1\",\"contentUrl\":\"https:\/\/i1.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/LOGO-EG-clair-1200.png?fit=1200%2C222&ssl=1\",\"width\":1200,\"height\":222,\"caption\":\"ergolabs group sprl\"},\"image\":{\"@id\":\"https:\/\/egroup.be\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/egroup.be\/#\/schema\/person\/fc2ba0627b169b6ea1d99818587a33df\",\"name\":\"Sacha Kocovski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/egroup.be\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f60eb59c8bc4c910cf54c201384ed5b1dc37d29630876dc09cc65c9271389ed1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f60eb59c8bc4c910cf54c201384ed5b1dc37d29630876dc09cc65c9271389ed1?s=96&d=mm&r=g\",\"caption\":\"Sacha Kocovski\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Int\u00e9gration de l\u2019ergonomie","description":"L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egroup.be\/fr\/integration-de-lergonomie-a-stade-entreprise\/","og_locale":"fr_FR","og_type":"article","og_title":"Int\u00e9gration de l\u2019ergonomie","og_description":"L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?","og_url":"https:\/\/egroup.be\/fr\/integration-de-lergonomie-a-stade-entreprise\/","og_site_name":"ergolabs group - UX \/ UI agency \/ usability","article_published_time":"2017-09-28T10:19:41+00:00","article_modified_time":"2018-04-30T09:24:08+00:00","og_image":[{"width":4000,"height":2667,"url":"https:\/\/i2.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1","type":"image\/jpeg"}],"author":"Sacha Kocovski","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sacha Kocovski","Dur\u00e9e de lecture est.":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#article","isPartOf":{"@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/"},"author":{"name":"Sacha Kocovski","@id":"https:\/\/egroup.be\/#\/schema\/person\/fc2ba0627b169b6ea1d99818587a33df"},"headline":"Int\u00e9gration de l\u2019ergonomie : \u00e0 quel stade est votre entreprise ?","datePublished":"2017-09-28T10:19:41+00:00","dateModified":"2018-04-30T09:24:08+00:00","mainEntityOfPage":{"@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/"},"wordCount":859,"publisher":{"@id":"https:\/\/egroup.be\/#organization"},"image":{"@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1","articleSection":["Articles","blog"],"inLanguage":"fr-BE"},{"@type":"WebPage","@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/","url":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/","name":"Int\u00e9gration de l\u2019ergonomie","isPartOf":{"@id":"https:\/\/egroup.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage"},"image":{"@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1","datePublished":"2017-09-28T10:19:41+00:00","dateModified":"2018-04-30T09:24:08+00:00","description":"L\u2019int\u00e9gration de l\u2019ergonomie au sein d\u2019une entreprise est souvent r\u00e9alis\u00e9e de mani\u00e8re s\u00e9quentielle et peut distinguer diff\u00e9rents stades de maturit\u00e9. Pouvez-vous placer votre entreprise sur cette \u00e9chelle ?","breadcrumb":{"@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#primaryimage","url":"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1","width":4000,"height":2667},{"@type":"BreadcrumbList","@id":"https:\/\/egroup.be\/integration-de-lergonomie-a-stade-entreprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/egroup.be\/"},{"@type":"ListItem","position":2,"name":"Int\u00e9gration de l\u2019ergonomie : \u00e0 quel stade est votre entreprise ?"}]},{"@type":"WebSite","@id":"https:\/\/egroup.be\/#website","url":"https:\/\/egroup.be\/","name":"ergolabs group - Agence UX\/UI - ergonomie","description":"","publisher":{"@id":"https:\/\/egroup.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egroup.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/egroup.be\/#organization","name":"ergolabs group sprl","url":"https:\/\/egroup.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/egroup.be\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/LOGO-EG-clair-1200.png?fit=1200%2C222&ssl=1","contentUrl":"https:\/\/i1.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/LOGO-EG-clair-1200.png?fit=1200%2C222&ssl=1","width":1200,"height":222,"caption":"ergolabs group sprl"},"image":{"@id":"https:\/\/egroup.be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/egroup.be\/#\/schema\/person\/fc2ba0627b169b6ea1d99818587a33df","name":"Sacha Kocovski","image":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/egroup.be\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f60eb59c8bc4c910cf54c201384ed5b1dc37d29630876dc09cc65c9271389ed1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f60eb59c8bc4c910cf54c201384ed5b1dc37d29630876dc09cc65c9271389ed1?s=96&d=mm&r=g","caption":"Sacha Kocovski"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/egroup.be\/wp-content\/uploads\/2018\/04\/pexels-photo-273230.jpeg?fit=4000%2C2667&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9cWzz-Ow","_links":{"self":[{"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/posts\/3132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/comments?post=3132"}],"version-history":[{"count":1,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/posts\/3132\/revisions"}],"predecessor-version":[{"id":3423,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/posts\/3132\/revisions\/3423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/media\/3233"}],"wp:attachment":[{"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/media?parent=3132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/categories?post=3132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/egroup.be\/fr\/wp-json\/wp\/v2\/tags?post=3132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}